{"id":23787,"date":"2025-08-05T07:32:01","date_gmt":"2025-08-05T07:32:01","guid":{"rendered":"https:\/\/playersforlife.com\/2025\/08\/05\/collection-rare-1-pour-evercade-annoncee\/"},"modified":"2025-08-05T07:33:20","modified_gmt":"2025-08-05T07:33:20","slug":"collection-rare-1-pour-evercade-annoncee","status":"publish","type":"post","link":"https:\/\/playersforlife.com\/fr\/2025\/08\/05\/collection-rare-1-pour-evercade-annoncee\/","title":{"rendered":"Collection Rare 1 pour Evercade annonc\u00e9e"},"content":{"rendered":"<div class=\"key-takeaways\"><h3>En quelques mots<\/h3><p>Cr\u00e9\u00e9 avec l&#039;IA - on travaille encore dessus ! D\u00e9sol\u00e9 si \u00e7a ne correspond pas tout \u00e0 fait \u00e0 vos attentes.<\/p><ul><li style=\"margin-bottom: 8px;\">Rare Studios c\u00e9l\u00e8bre son 40e anniversaire avec la sortie de Rare Collection 1 pour Evercade Systems le 1er novembre.<\/li><li style=\"margin-bottom: 8px;\">La collection comprend 12 jeux, y compris certains des classiques les plus anciens et les plus appr\u00e9ci\u00e9s de Rare sur ZX Spectrum et d&#039;autres consoles 8 bits.<\/li><li style=\"margin-bottom: 8px;\">La cartouche The Rare Collection 1 est compatible avec plusieurs appareils : les consoles Evercade VS, les p\u00e9riph\u00e9riques Evercade EXP, les bornes d\u2019arcade Evercade Alpha et les appareils portables HyperMegaTech Super Pocket.<\/li><li style=\"margin-bottom: 8px;\">La collection est tarif\u00e9e \u00e0 29 \u00a3<\/li><\/ul><\/div>\n<h2>F\u00eatez le 40\u00e8me anniversaire de Rare Studios avec la sortie de la collection Classic 12 jeux d&rsquo;Evercade le 1er novembre<\/h2>\n<p>\u00c0 l&rsquo;occasion du 40\u00e8me anniversaire de Rare Studios, Blaze Entertainment sort Rare Collection 1 pour Evercade Systems le 1er novembre au prix de 29 \u20ac. Cette collection de 12 jeux comprend certains des plus grands classiques de Rare, y compris les titres provenant de la ZX Spectrum et d&rsquo;autres versions console 8 bits. La cartouche Rare Collection 1 est compatible avec les consoles Evercade VS, les appareils Evercade EXP, les machines d&rsquo;arcade Evercade Alpha et les dispositifs portables HyperMegaTech Super Pocket.<\/p>\n<p><iframe title=\"Evercade Rare Collection 1 Trailer (Full list in Description) #evercade #xbox #battletoads #rare\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/NKamf9Fjxms?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rejoignez Blaze Entertainment pour c\u00e9l\u00e9brer le 40\u00e8me anniversaire de Rare Studios le 1er novembre ! Revivez des moments de jeu classiques avec la collection Rare 1, disponible d\u00e8s maintenant au prix de \u20ac29 sur plusieurs syst\u00e8mes Evercade.<\/p>\n","protected":false},"author":10,"featured_media":23780,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","movie_schema":"","tvshow_schema":"","videogame_schema":"","meta_description":"Collection Rare 1 : 12 jeux vintage sur Evercade d\u00e8s le 1er novembre","meta_keywords":"rare-collection-1, jeux-retro, evercade-compatible, rare-studios-anniversaire, zx-spectrum","meta_author":"Antoine Vincent","meta_robots":"index, follow","meta_language":"en","twitter_card":"summary_large_image","twitter_title":"Rare Collection 1 : 12 jeux vintage sur Evercade","twitter_description":"D\u00e9couvrez la Collection Rare 1 pour Evercade : une s\u00e9lection de 12 jeux rares de Rare Entertainment, incluant des classiques des ann\u00e9es 80, disponible d\u00e8s le 1er novembre au prix de \u20ac29. Compatible avec les syst\u00e8mes Evercade Vs et Exp, ainsi que les machines Alpha et Super Pocket Hypermegatech. Ne manquez pas cette occasion unique de jouer \u00e0 des titres introuvables ailleurs !","twitter_site":"","twitter_site_id":"","twitter_creator":"","twitter_creator_id":"","twitter_image":"https:\/\/assetsio.gnwcdn.com\/Evercade-Rare-Collection-1-1920x1080-header-(1).webp","twitter_image_alt":"","twitter_app_name_iphone":"","twitter_app_id_iphone":"","twitter_app_url_iphone":"","twitter_app_name_ipad":"","twitter_app_id_ipad":"","twitter_app_url_ipad":"","twitter_app_name_googleplay":"","twitter_app_id_googleplay":"","twitter_app_url_googleplay":"","twitter_player":"","twitter_player_width":0,"twitter_player_height":0,"twitter_player_stream":"","og_title":"Rare Collection 1 : 12 jeux vintage sur Evercade","og_type":"article","og_url":"https:\/\/playersforlife.com\/fr\/2025\/08\/05\/collection-rare-1-pour-evercade-annoncee\/","og_image":"https:\/\/assetsio.gnwcdn.com\/Evercade-Rare-Collection-1-1920x1080-header-(1).webp","og_image_secure_url":"https:\/\/assetsio.gnwcdn.com\/Evercade-Rare-Collection-1-1920x1080-header-(1).webp","og_image_type":"image\/webp","og_image_width":0,"og_image_height":0,"og_image_alt":"","og_description":"D\u00e9couvrez la Collection Rare 1 pour Evercade : une s\u00e9lection de 12 jeux rares de Rare Entertainment, incluant des classiques des ann\u00e9es 80, disponible d\u00e8s le 1er novembre au prix de \u20ac29. Compatible avec les syst\u00e8mes Evercade Vs et Exp, ainsi que les machines Alpha et Super Pocket Hypermegatech. Ne manquez pas cette occasion unique de jouer \u00e0 des titres introuvables ailleurs !","og_site_name":"PlayersForLife.com","og_locale":"en_US","og_article_published_time":"2025-08-05T07:33:01","og_article_modified_time":"2025-08-05T07:33:01","og_article_author":"Antoine Vincent","og_article_section":"Releases","og_article_tag":["Mixed"],"og_video":"https:\/\/www.youtube.com\/embed\/iWq8EOwLFrk","og_video_secure_url":"https:\/\/www.youtube.com\/embed\/iWq8EOwLFrk","og_video_type":"","og_video_width":0,"og_video_height":0,"og_audio":"","og_audio_secure_url":"","og_audio_type":"","footnotes":""},"categories":[40],"tags":[45,48],"class_list":["post-23787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-releases","tag-mixed","tag-rpg"],"lang":"fr","original_post_id":null,"featured_image_urls":{"full":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",1920,1080,false],"thumbnail":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1-150x150.webp",150,150,true],"medium":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1-300x169.webp",300,169,true],"medium_large":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1-768x432.webp",768,432,true],"large":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1-1024x576.webp",1024,576,true],"1536x1536":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1-1536x864.webp",1536,864,true],"2048x2048":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",1920,1080,false],"penci-single-full":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",1920,1080,false],"penci-slider-full-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",1422,800,false],"penci-full-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",1170,658,false],"penci-slider-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",1170,658,false],"penci-magazine-slider":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",780,439,false],"penci-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",585,329,false],"penci-masonry-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",585,329,false],"penci-thumb-square":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",585,329,false],"penci-thumb-vertical":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",480,270,false],"penci-thumb-small":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",263,148,false],"penci-recipe-1200x1200":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",1200,675,false],"penci-recipe-1200x900":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",1200,675,false],"penci-recipe-1200x675":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/08\/Evercade-Rare-Collection-1-1920x1080-header-1.webp",1200,675,false]},"author_info":{"info":["Antoine Vincent"]},"category_info":"<a href=\"https:\/\/playersforlife.com\/category\/releases\/\" rel=\"category tag\">Releases<\/a>","tag_info":"Releases","comment_count":"0","_links":{"self":[{"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/posts\/23787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/comments?post=23787"}],"version-history":[{"count":1,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/posts\/23787\/revisions"}],"predecessor-version":[{"id":23788,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/posts\/23787\/revisions\/23788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/media\/23780"}],"wp:attachment":[{"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/media?parent=23787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/categories?post=23787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/tags?post=23787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}