{"id":134006,"date":"2026-03-28T14:31:06","date_gmt":"2026-03-28T14:31:06","guid":{"rendered":"https:\/\/playersforlife.com\/2026\/03\/28\/saros-plus-accessible-que-returnal-pour-faciliter-l-experience-des-joueurs\/"},"modified":"2026-03-28T14:43:43","modified_gmt":"2026-03-28T14:43:43","slug":"saros-plus-accessible-que-returnal-pour-faciliter-l-experience-des-joueurs","status":"publish","type":"post","link":"https:\/\/playersforlife.com\/fr\/2026\/03\/28\/saros-plus-accessible-que-returnal-pour-faciliter-l-experience-des-joueurs\/","title":{"rendered":"Saros : Plus accessible que Returnal pour faciliter l&rsquo;exp\u00e9rience des joueurs"},"content":{"rendered":"<p><div class=\"key-takeaways\"><h3>En quelques mots<\/h3><p>Cr\u00e9\u00e9 avec l&#039;IA - on travaille encore dessus ! D\u00e9sol\u00e9 si \u00e7a ne correspond pas tout \u00e0 fait \u00e0 vos attentes.<\/p><ul><li style=\"margin-bottom: 8px;\">Contraintes:<\/li><li style=\"margin-bottom: 8px;\">Les phases en Saros sont con\u00e7ues pour \u00eatre plus courtes (en moyenne 20-30 minutes) que celles de Returnal, offrant ainsi une exp\u00e9rience d&#039;apprentissage plus fr\u00e9quente. Le deuxi\u00e8me biome comprendra des t\u00e9l\u00e9porteurs d\u00e9verrouillables pour gagner du temps lors des essais \u00e0 nouveau.<\/li><li style=\"margin-bottom: 8px;\">Saros comprend des m\u00e9caniques de seconde chance et des modificateurs carcosans qui alt\u00e8rent le jeu pendant les parties, offrant aux joueurs des occasions de r\u00e9surrection et ajustant le niveau de difficult\u00e9.<\/li><li style=\"margin-bottom: 8px;\">Saros sortira prochainement en tant qu&#039;exclusivit\u00e9 PlayStation 5, avec des niveaux, de l&#039;art, une conception et des combats g\u00e9n\u00e9r\u00e9s proc\u00e9duralement, ainsi qu&#039;une histoire captivante avec les voix de Rahul Kohli (Arjun Devraj), Jane Perry (Selene) et d&#039;autres talents familiers du jeu Returnal.<\/li><\/ul><\/div><br \/>\n<h3>Recommended products<\/h3><p class=\"aws-affiliate-disclaimer\">This page contains affiliate links. As an Amazon Associate, we earn a commission from purchases made through these links.<\/p><div class=\"aws-product-grid\"><div class=\"aws-product-card\"><div class=\"aws-product-image\"><a href=\"https:\/\/www.amazon.com\/JUSPRO-Enhanced-Adjustable-Accessories-PlayStation\/dp\/B0DZXFP9Q3\/ref=sr_1_3?tag=playersforlif-20\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/m.media-amazon.com\/images\/I\/71G+Kl+jl8L._SX522_.jpg\" alt=\"JUSPRO Cooling Fan for PS5 Pro, Quiet Enhanced 4 Cooler Fan with Adjustable Speed, Auto Power On\/Off, Cooling Accessories with USB 3.0 Port and LED Light for PlayStation 5 Pro\" title=\"\"><\/a><\/div><div class=\"aws-product-content\"><h4><a href=\"https:\/\/www.amazon.com\/JUSPRO-Enhanced-Adjustable-Accessories-PlayStation\/dp\/B0DZXFP9Q3\/ref=sr_1_3?tag=playersforlif-20\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">JUSPRO Cooling Fan for PS5 Pro, Quiet Enhanced 4 Cooler Fan with Adjustable Speed, Auto Power On\/Off, Cooling Accessories with USB 3.0 Port and LED Light for PlayStation 5 Pro<\/a><\/h4><div class=\"aws-product-prices\"><span class=\"aws-current-price\">$24.99<\/span><\/div><\/div><\/div><\/div>\n        <style>\n            .aws-affiliate-disclaimer {\n                font-size: 13px;\n                color: #666;\n                margin: 4px 0 16px 0;\n            }\n\n            .aws-product-grid {\n                display: grid;\n                grid-template-columns: repeat(3, 1fr);\n                gap: 20px;\n                margin: 20px 0;\n            }\n            \n            .aws-product-card {\n                border: 1px solid #e0e0e0;\n                border-radius: 8px;\n                overflow: hidden;\n                background: #fff;\n                box-shadow: 0 2px 4px rgba(0,0,0,0.1);\n                transition: transform 0.2s ease, box-shadow 0.2s ease;\n                position: relative;\n            }\n            \n            .aws-product-card:hover {\n                transform: translateY(-2px);\n                box-shadow: 0 4px 8px rgba(0,0,0,0.15);\n            }\n            \n            .aws-discount-badge {\n                position: absolute;\n                top: 10px;\n                right: 10px;\n                background: #ff4444;\n                color: white;\n                padding: 4px 8px;\n                border-radius: 4px;\n                font-size: 12px;\n                font-weight: bold;\n                z-index: 2;\n            }\n            \n            .aws-product-image {\n                width: 100%;\n                height: 200px;\n                overflow: hidden;\n                background: #f5f5f5;\n            }\n            \n            .aws-product-image img {\n                width: 100%;\n                height: 100%;\n                object-fit: contain;\n                transition: transform 0.2s ease;\n            }\n            \n            .aws-product-image:hover img {\n                transform: scale(1.05);\n            }\n            \n            .aws-product-image a {\n                display: block;\n                width: 100%;\n                height: 100%;\n            }\n            \n            .aws-product-content {\n                padding: 15px;\n            }\n            \n            .aws-product-content h4 {\n                margin: 0 0 10px 0;\n                font-size: 16px;\n                line-height: 1.3;\n            }\n            \n            .aws-product-content h4 a {\n                color: #333;\n                text-decoration: none;\n                transition: color 0.2s ease;\n            }\n            \n            .aws-product-content h4 a:hover {\n                color: #0073aa;\n            }\n            \n            .aws-product-prices {\n                display: flex;\n                align-items: center;\n                gap: 8px;\n                font-weight: bold;\n            }\n            \n            .aws-original-price {\n                text-decoration: line-through;\n                color: #999;\n                font-size: 14px;\n            }\n            \n            .aws-discounted-price {\n                color: #ff4444;\n                font-size: 16px;\n            }\n            \n            .aws-current-price {\n                color: #333;\n                font-size: 16px;\n            }\n            \n            \/* Tablet styles - 2 columns *\/\n            @media (max-width: 768px) {\n                .aws-product-grid {\n                    grid-template-columns: repeat(2, 1fr);\n                    gap: 15px;\n                }\n                \n                .aws-product-image {\n                    height: 180px;\n                }\n            }\n            \n            \/* Mobile styles - 1 column *\/\n            @media (max-width: 480px) {\n                .aws-product-grid {\n                    grid-template-columns: 1fr;\n                    gap: 15px;\n                }\n                \n                .aws-product-image {\n                    height: 220px;\n                }\n                \n                .aws-product-content {\n                    padding: 12px;\n                }\n            }\n        <\/style><\/p>\n<p>Housemarque&rsquo;s upcoming science fiction roguelike, Saros, is designed to be more accessible than Returnal, largely due to direct player feedback. Creative director Gregory Louden explained that the team recognized players \u00ab\u00a0loved what we created, but\u2026 wanted to get further.\u00a0\u00bb To help players progress, Saros will include features like autosaves, multiple save slots, and the ability to pause the game\u2014something that wasn&rsquo;t available in Returnal at launch. Louden maintains that increased accessibility doesn&rsquo;t mean an easy game. \u00ab\u00a0For us, it&rsquo;s about providing that capability\u2026 it remains a very challenging game, but there&rsquo;s also the ability to modify the challenge in some way.\u00a0\u00bb Saros will feature procedurally generated levels, art, design, and combat encounters. Development began after the release of Returnal&rsquo;s Ascension DLC. The initial team included Louden, art director Ville Kinnunen (also from Returnal), Henri Mustonen, and Harry Krueger\u2014Returnal&rsquo;s director, who departed Housemarque in 2023. In Saros, players earn experience points during exploration to permanently upgrade the character Arjun Devraj at their base. Players must defeat bosses to unlock further upgrades. Rahul Kohli stars as Arjun Devraj, contributing to the storyline with his feedback. Jane Perry, who played Selene in Returnal, is also part of the cast.<\/p>\n<h2>Courtes parties et m\u00e9caniques de deuxi\u00e8me chance dans Saros, une exp\u00e9rience d&rsquo;apprentissage plus fr\u00e9quente sur Playstation 5<\/h2>\n<p>Le directeur de jeu principal Abebe Tinari a d\u00e9clar\u00e9 que les passages \u00e0 travers un biome de Saros dureront en moyenne 20-30 minutes &#8211; beaucoup plus courts que les passages parfois d&rsquo;une heure dans Returnal. Le directeur adjoint de la conception Mitja Roskaric a expliqu\u00e9 : \u00ab\u00a0C&rsquo;est une exp\u00e9rience difficile, mais chaque fois que quelqu&rsquo;un meurt, nous voulons qu&rsquo;ils tirent quelque chose de cela&#8230; Avec des tentatives plus courtes, je pense qu&rsquo;il est plus facile de recueillir plus de le\u00e7ons fr\u00e9quemment. C&rsquo;est pourquoi je pense que les sessions de 30 minutes sont id\u00e9ales pour ce type d&rsquo;exp\u00e9rience\u00a0\u00bb. Le deuxi\u00e8me biome comprendra des t\u00e9l\u00e9porteurs d\u00e9blocables pour \u00e9conomiser du temps lors des reprises. Saros inclura \u00e9galement des m\u00e9caniques de deuxi\u00e8me chance (r\u00e9surrection) et des modificateurs Carcosans qui alt\u00e8rent le gameplay pendant les passages. Contrairement \u00e0 la sortie initiale de Returnal &#8211; qui n\u00e9cessitait l&rsquo;ach\u00e8vement d&rsquo;une seule partie \u00e0 la fois, une limitation sp\u00e4tere corrig\u00e9e dans la mise \u00e0 jour 2.0 -, Saros offrira des \u00e9conomies automatiques d\u00e8s le premier jour. Saros, exclusivit\u00e9 PlayStation 5, est pr\u00e9vu pour sortir prochainement en avril, suite \u00e0 un l\u00e9ger report fin de l&rsquo;ann\u00e9e derni\u00e8re.<\/p>\n<h2>Au cas o\u00f9 vous l&rsquo;auriez manqu\u00e9<\/h2>\n<p>Au fur et \u00e0 mesure que nous plongeons dans le monde color\u00e9 de PlayStation, Marcus Thompson nous emm\u00e8ne dans une balade palpitante avec son dernier article, &lsquo;Saros Gets New Gameplay Trailer&rsquo; <a href=\"https:\/\/playersforlife.com\/fr\/2026\/03\/18\/saros-recoit-une-nouvelle-bande-annonce-de-gameplay\/\" target=\"_blank\" rel=\"noopener noreferrer\">Saros re\u00e7oit une nouvelle bande-annonce de gameplay<\/a>. Publi\u00e9 le 18 mars, c&rsquo;est un must-read pour les fans avides de d\u00e9couvrir l&rsquo;exclusivit\u00e9 PS5 rapide de Housemarque. Thompson nous immerge dans l&rsquo;action dynamique de Saros, mettant en valeur comment le jeu pousse les limites avec le feedback Dynamic Trigger et l&rsquo;audio 3D. Dans le m\u00eame temps, Jonathan Dubinski \u00e9claire sur le paysage \u00e9voluant de Sony avec son article complet, &lsquo;All Studios Closed by PlayStation Since the Launch of PS5&rsquo;, publi\u00e9 le 26 mars <a href=\"https:\/\/playersforlife.com\/fr\/2026\/03\/26\/tous-les-studios-fermes-par-playstation-depuis-le-lancement-de-la-ps5\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tous les studios ferm\u00e9s par PlayStation depuis le lancement de la PS5<\/a>. Cette plong\u00e9e fascinante explore les huit studios qui ont ferm\u00e9 entre 2020 et 2026, offrant des aper\u00e7us sur les dynamiques changeantes de l&rsquo;industrie. Et dans une r\u00e9cente r\u00e9v\u00e9lation, Sophie Laurent (Players for Life, 5 mars 2026) explore le virage strat\u00e9gique de Sony avec son article, \u00ab\u00a0Sony Reversing Course on PC to Safeguard Solo Exclusives, With PlayStation 6 in Sight\u00a0\u00bb <a href=\"https:\/\/playersforlife.com\/fr\/2026\/03\/05\/sony-change-de-cap-sur-le-pc-pour-preserver-ses-exclusivites-solitaires-avec-la-ps6-en-ligne-de-mire\/\" target=\"_blank\" rel=\"noopener noreferrer\">Sony change de cap sur le PC pour pr\u00e9server ses exclusivit\u00e9s solitaires, avec la PS6 en ligne de mire<\/a>. Laurent s&rsquo;enfonce dans les rapports de Jason Schreier, indiquant le mouvement de Sony loin des sorties simultan\u00e9es sur PC pour les exclusivit\u00e9s majeures comme Horizon Zero Dawn et God of War, alors qu&rsquo;ils naviguent l&rsquo;\u00e9quilibre entre la pr\u00e9servation de la valeur des exclusivit\u00e9s consoles et l&rsquo;exploration de nouveaux flux de revenus.<\/p>\n<p><img decoding=\"async\" style=\"width: 100%\" src=\"https:\/\/blog.br.playstation.com\/tachyon\/sites\/4\/2025\/12\/ae52b060fab10c2d37fba2add6b4113a47228c94.jpg?resize=1088%2C612&amp;crop_strategy=smart\" alt=\"\" title=\"\"><br \/>\n<div class=\"external-references\"><h2>Ils en parlent aussi dans la presse \u00e9trang\u00e8re<\/h2><p class=\"external-references__disclaimer\">Si vous comprenez l&#039;anglais, voici des liens vers des sources externes<\/p><ul class=\"external-references__list\"><li class=\"external-references__item\" data-index=\"1\"><span class=\"external-references__title\">&#039;Our story is built to be haunting, interpretive, and ambiguous&#039;<\/span><a href=\"https:\/\/www.videogameschronicle.com\/features\/housemarque-on-how-saros-evolves-returnals-punishing-formula\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" class=\"external-references__link\"><span class=\"external-references__title\">&#039;Our story is built to be haunting, interpretive, and ambiguous&#039;<\/span><span class=\"external-references__domain\">videogameschronicle.com<\/span><\/a><\/li><li class=\"external-references__item\" data-index=\"2\"><span class=\"external-references__title\">Teleportation Solutions<\/span><a href=\"https:\/\/www.gamespot.com\/articles\/saros-looks-like-returnal-but-feels-unlike-anything-else-housemarque-has-made\/1100-6538988\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" class=\"external-references__link\"><span class=\"external-references__title\">Teleportation Solutions<\/span><span class=\"external-references__domain\">gamespot.com<\/span><\/a><\/li><li class=\"external-references__item\" data-index=\"3\"><span class=\"external-references__title\">Saros developer doesn&#039;t think Returnal &#039;was that hard of a game&#039;, but admits that the team &#039;did pay a lot more attention to the onboarding experience&#039; for its spiritual successor<\/span><a href=\"https:\/\/mobilesyrup.com\/2026\/03\/26\/housemarque-saros-ps5-preview\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" class=\"external-references__link\"><span class=\"external-references__title\">Saros developer doesn&#039;t think Returnal &#039;was that hard of a game&#039;, but admits that the team &#039;did pay a lot more attention to the onboarding experience&#039; for its spiritual successor<\/span><span class=\"external-references__domain\">mobilesyrup.com<\/span><\/a><\/li><\/ul><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le prochain jeu de tir \u00e0 la troisi\u00e8me personne en monde ouvert de Housemarque, Returnal, propose une exp\u00e9rience de jeu plus accessible et plus facile \u00e0 ma\u00eetriser gr\u00e2ce aux fonctionnalit\u00e9s d&rsquo;auto-sauvegarde et aux nombreuses fentes de sauvegarde disponibles, ainsi qu&rsquo;aux sessions plus courtes con\u00e7ues pour permettre un apprentissage r\u00e9gulier des erreurs tout en maintenant l&rsquo;intensit\u00e9 de son pr\u00e9d\u00e9cesseur.<\/p>\n","protected":false},"author":10,"featured_media":133999,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","movie_schema":"","tvshow_schema":"","videogame_schema":"","meta_description":"\"D\u00e9couvrez 'Outlast', un jeu de tir \u00e0 la troisi\u00e8me personne avec des \u00e9l\u00e9ments RPG et action, se d\u00e9roulant dans un h\u00f4pital psychiatrique abandonn\u00e9. Utilisez votre appareil photo pour explorer les lieux sombres et \u00e9vitez les patients fous meurtriers gr\u00e2ce \u00e0 une cam\u00e9ra en premi\u00e8re personne et \u00e0 la fonction de vision nocturne. Vivre l'exp\u00e9rience terrifiante et stressante de 'Outlast' !\"","meta_keywords":"outlast, jeu horreur, action rpg, exploration, appareil photo, Patients fous, vision nocturne","meta_author":"Antoine Vincent","meta_robots":"index, follow","meta_language":"en","twitter_card":"summary_large_image","twitter_title":"Saros : L'exp\u00e9rience de jeu plus accessible que Returnal","twitter_description":"D\u00e9couvrez \"Outlast\", le jeu de tir \u00e0 la troisi\u00e8me personne avec des \u00e9l\u00e9ments RPG et action, o\u00f9 vous devrez explorer un h\u00f4pital psychiatrique abandonn\u00e9 pour \u00e9viter les patients meurtriers dans une ambiance effrayante et immersive. Utilisez votre appareil photo pour d\u00e9voiler l'histoire sombre de Mount Massive.","twitter_site":"","twitter_site_id":"","twitter_creator":"","twitter_creator_id":"","twitter_image":"https:\/\/assetsio.gnwcdn.com\/Saros-PS5.png","twitter_image_alt":"","twitter_app_name_iphone":"","twitter_app_id_iphone":"","twitter_app_url_iphone":"","twitter_app_name_ipad":"","twitter_app_id_ipad":"","twitter_app_url_ipad":"","twitter_app_name_googleplay":"","twitter_app_id_googleplay":"","twitter_app_url_googleplay":"","twitter_player":"","twitter_player_width":0,"twitter_player_height":0,"twitter_player_stream":"","og_title":"Saros : L'exp\u00e9rience de jeu plus accessible que Returnal","og_type":"article","og_url":"https:\/\/playersforlife.com\/fr\/2026\/03\/28\/saros-plus-accessible-que-returnal-pour-faciliter-l-experience-des-joueurs\/","og_image":"https:\/\/assetsio.gnwcdn.com\/Saros-PS5.png","og_image_secure_url":"https:\/\/assetsio.gnwcdn.com\/Saros-PS5.png","og_image_type":"image\/png","og_image_width":0,"og_image_height":0,"og_image_alt":"","og_description":"D\u00e9couvrez \"Outlast\", le jeu de tir \u00e0 la troisi\u00e8me personne avec des \u00e9l\u00e9ments RPG et action, o\u00f9 vous devrez explorer un h\u00f4pital psychiatrique abandonn\u00e9 pour \u00e9viter les patients meurtriers dans une ambiance effrayante et immersive. Utilisez votre appareil photo pour d\u00e9voiler l'histoire sombre de Mount Massive.","og_site_name":"PlayersForLife.com","og_locale":"en_US","og_article_published_time":"2026-03-28T14:31:06","og_article_modified_time":"2026-03-28T14:31:06","og_article_author":"Antoine Vincent","og_article_section":"News","og_article_tag":["Action"],"og_video":"https:\/\/www.youtube.com\/embed\/U1jP_AjjhZs","og_video_secure_url":"https:\/\/www.youtube.com\/embed\/U1jP_AjjhZs","og_video_type":"","og_video_width":0,"og_video_height":0,"og_audio":"","og_audio_secure_url":"","og_audio_type":"","footnotes":""},"categories":[38],"tags":[42,43],"class_list":["post-134006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-action","tag-adventure"],"lang":"fr","original_post_id":null,"featured_image_urls":{"full":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06.png",1280,720,false],"thumbnail":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-150x150.png",150,150,true],"medium":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-300x169.png",300,169,true],"medium_large":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-768x432.png",768,432,true],"large":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-1024x576.png",1024,576,true],"1536x1536":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06.png",1280,720,false],"2048x2048":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06.png",1280,720,false],"penci-single-full":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06.png",1280,720,false],"penci-slider-full-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06.png",1280,720,false],"penci-full-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-1170x658.png",1170,658,true],"penci-slider-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-1170x663.png",1170,663,true],"penci-magazine-slider":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-780x516.png",780,516,true],"penci-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-585x390.png",585,390,true],"penci-masonry-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-585x329.png",585,329,true],"penci-thumb-square":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-585x585.png",585,585,true],"penci-thumb-vertical":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-480x650.png",480,650,true],"penci-thumb-small":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-263x175.png",263,175,true],"penci-recipe-1200x1200":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-1200x720.png",1200,720,true],"penci-recipe-1200x900":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-1200x720.png",1200,720,true],"penci-recipe-1200x675":["https:\/\/playersforlife.com\/wp-content\/uploads\/2026\/03\/image_2026-03-Mar-28-2026_10-41-06-1200x675.png",1200,675,true]},"author_info":{"info":["Antoine Vincent"]},"category_info":"<a href=\"https:\/\/playersforlife.com\/category\/news\/\" rel=\"category tag\">News<\/a>","tag_info":"News","comment_count":"0","_links":{"self":[{"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/posts\/134006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/comments?post=134006"}],"version-history":[{"count":1,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/posts\/134006\/revisions"}],"predecessor-version":[{"id":134007,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/posts\/134006\/revisions\/134007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/media\/133999"}],"wp:attachment":[{"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/media?parent=134006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/categories?post=134006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/playersforlife.com\/fr\/wp-json\/wp\/v2\/tags?post=134006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}