{"id":55765,"date":"2025-09-22T14:35:44","date_gmt":"2025-09-22T14:35:44","guid":{"rendered":"https:\/\/playersforlife.com\/2025\/09\/22\/borderlands-4-ya-ha-conquistado-a-mas-de-2-5-millones-de-jugadores\/"},"modified":"2025-09-22T14:38:30","modified_gmt":"2025-09-22T14:38:30","slug":"borderlands-4-ya-ha-conquistado-a-mas-de-2-5-millones-de-jugadores","status":"publish","type":"post","link":"https:\/\/playersforlife.com\/es\/2025\/09\/22\/borderlands-4-ya-ha-conquistado-a-mas-de-2-5-millones-de-jugadores\/","title":{"rendered":"Borderlands 4 ya ha conquistado a m\u00e1s de 2,5 millones de jugadores"},"content":{"rendered":"<p><div class=\"key-takeaways\"><h3>Puntos clave<\/h3><p>Creado con IA - todav\u00eda estamos experimentando, as\u00ed que disculpa si no cumple con tus expectativas.<\/p><ul><li style=\"margin-bottom: 8px;\">Borderlands 4 ha obtenido un gran \u00e9xito de ventas, generando m\u00e1s de 150 millones de d\u00f3lares a nivel mundial y vendiendo m\u00e1s de 2,5 millones de unidades.<\/li><li style=\"margin-bottom: 8px;\">La versi\u00f3n para PC del juego present\u00f3 inicialmente problemas de rendimiento, pero se planean actualizaciones para abordar estas preocupaciones.<\/li><li style=\"margin-bottom: 8px;\">El CEO de Gearbox, Randy Pitchford, ha sugerido que los clientes insatisfechos pueden solicitar reembolsos debido a los problemas de rendimiento.<\/li><li style=\"margin-bottom: 8px;\">La mayor\u00eda de los jugadores est\u00e1n basados en Estados Unidos, siendo un gran n\u00famero veteranos de la serie procedentes de juegos anteriores de Borderlands.<\/li><\/ul><\/div><br \/>\n<h3>Recommended products<\/h3><p class=\"aws-affiliate-disclaimer\">This page contains affiliate links. As an Amazon Associate, we earn a commission from purchases made through these links.<\/p><div class=\"aws-product-grid\"><div class=\"aws-product-card\"><div class=\"aws-product-image\"><a href=\"https:\/\/www.amazon.com\/Borderlands-4-Super-Deluxe-PlayStation-5\/dp\/B0FDBLLB34\/ref=sr_1_1?tag=playersforlif-20\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/m.media-amazon.com\/images\/I\/81yBfCSVvrL._AC_UL320_.jpg\" alt=\"Borderlands 4 Super Deluxe Edition - PlayStation 5\" title=\"\"><\/a><\/div><div class=\"aws-product-content\"><h4><a href=\"https:\/\/www.amazon.com\/Borderlands-4-Super-Deluxe-PlayStation-5\/dp\/B0FDBLLB34\/ref=sr_1_1?tag=playersforlif-20\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Borderlands 4 Super Deluxe Edition - PlayStation 5<\/a><\/h4><div class=\"aws-product-prices\"><span class=\"aws-current-price\">$129.99<\/span><\/div><\/div><\/div><div class=\"aws-product-card\"><div class=\"aws-discount-badge\">-5%<\/div><div class=\"aws-product-image\"><a href=\"https:\/\/www.amazon.com\/Official-Borderlands-LookSee-Collector-Mystery\/dp\/B082LZVHB2\/ref=sr_1_2?tag=playersforlif-20\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/m.media-amazon.com\/images\/I\/71fYDmP2WtL._AC_UL320_.jpg\" alt=\"JUST FUNKY Official Borderlands LookSee Collector Mystery Gift Box - Includes Claptrap Blanket, Lanyard, Water Bottle, and More - Exclusive Fan Toy Collectible Set | Licensed Merchandise\" title=\"\"><\/a><\/div><div class=\"aws-product-content\"><h4><a href=\"https:\/\/www.amazon.com\/Official-Borderlands-LookSee-Collector-Mystery\/dp\/B082LZVHB2\/ref=sr_1_2?tag=playersforlif-20\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">JUST FUNKY Official Borderlands LookSee Collector Mystery Gift Box - Includes Claptrap Blanket, Lanyard, Water Bottle, and More - Exclusive Fan Toy Collectible Set | Licensed Merchandise<\/a><\/h4><div class=\"aws-product-prices\"><span class=\"aws-original-price\">$58.99<\/span><span class=\"aws-discounted-price\">$56.04<\/span><\/div><\/div><\/div><div class=\"aws-product-card\"><div class=\"aws-product-image\"><a href=\"https:\/\/www.amazon.com\/Official-Borderlands-LookSee-Collector-Mystery\/dp\/B082LSK53B\/ref=sr_1_3?tag=playersforlif-20\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/m.media-amazon.com\/images\/I\/81GmuwOk0SL._AC_UL320_.jpg\" alt=\"Just Funky Official Borderlands LookSee Collector Mystery Gift Box - Includes Psycho Blanket, Lanyard, Water Bottle, and More - Exclusive Fan Toy Collectibles Set | Licensed Merchandise\" title=\"\"><\/a><\/div><div class=\"aws-product-content\"><h4><a href=\"https:\/\/www.amazon.com\/Official-Borderlands-LookSee-Collector-Mystery\/dp\/B082LSK53B\/ref=sr_1_3?tag=playersforlif-20\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Just Funky Official Borderlands LookSee Collector Mystery Gift Box - Includes Psycho Blanket, Lanyard, Water Bottle, and More - Exclusive Fan Toy Collectibles Set | Licensed Merchandise<\/a><\/h4><div class=\"aws-product-prices\"><span class=\"aws-current-price\">$59.99<\/span><\/div><\/div><\/div><div class=\"aws-product-card\"><div class=\"aws-product-content\"><h4><a href=\"https:\/\/www.amazon.com\/Youtooz-Jabber-Plush-Borderlands-Plushie\/dp\/B0F38DG2BR\/ref=sr_1_4?tag=playersforlif-20\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Youtooz Jabber 9<\/a><\/h4><\/div><\/div><\/div>\n        <style>\n            .aws-affiliate-disclaimer {\n                font-size: 13px;\n                color: #666;\n                margin: 4px 0 16px 0;\n            }\n\n            .aws-product-grid {\n                display: grid;\n                grid-template-columns: repeat(3, 1fr);\n                gap: 20px;\n                margin: 20px 0;\n            }\n            \n            .aws-product-card {\n                border: 1px solid #e0e0e0;\n                border-radius: 8px;\n                overflow: hidden;\n                background: #fff;\n                box-shadow: 0 2px 4px rgba(0,0,0,0.1);\n                transition: transform 0.2s ease, box-shadow 0.2s ease;\n                position: relative;\n            }\n            \n            .aws-product-card:hover {\n                transform: translateY(-2px);\n                box-shadow: 0 4px 8px rgba(0,0,0,0.15);\n            }\n            \n            .aws-discount-badge {\n                position: absolute;\n                top: 10px;\n                right: 10px;\n                background: #ff4444;\n                color: white;\n                padding: 4px 8px;\n                border-radius: 4px;\n                font-size: 12px;\n                font-weight: bold;\n                z-index: 2;\n            }\n            \n            .aws-product-image {\n                width: 100%;\n                height: 200px;\n                overflow: hidden;\n                background: #f5f5f5;\n            }\n            \n            .aws-product-image img {\n                width: 100%;\n                height: 100%;\n                object-fit: contain;\n                transition: transform 0.2s ease;\n            }\n            \n            .aws-product-image:hover img {\n                transform: scale(1.05);\n            }\n            \n            .aws-product-image a {\n                display: block;\n                width: 100%;\n                height: 100%;\n            }\n            \n            .aws-product-content {\n                padding: 15px;\n            }\n            \n            .aws-product-content h4 {\n                margin: 0 0 10px 0;\n                font-size: 16px;\n                line-height: 1.3;\n            }\n            \n            .aws-product-content h4 a {\n                color: #333;\n                text-decoration: none;\n                transition: color 0.2s ease;\n            }\n            \n            .aws-product-content h4 a:hover {\n                color: #0073aa;\n            }\n            \n            .aws-product-prices {\n                display: flex;\n                align-items: center;\n                gap: 8px;\n                font-weight: bold;\n            }\n            \n            .aws-original-price {\n                text-decoration: line-through;\n                color: #999;\n                font-size: 14px;\n            }\n            \n            .aws-discounted-price {\n                color: #ff4444;\n                font-size: 16px;\n            }\n            \n            .aws-current-price {\n                color: #333;\n                font-size: 16px;\n            }\n            \n            \/* Tablet styles - 2 columns *\/\n            @media (max-width: 768px) {\n                .aws-product-grid {\n                    grid-template-columns: repeat(2, 1fr);\n                    gap: 15px;\n                }\n                \n                .aws-product-image {\n                    height: 180px;\n                }\n            }\n            \n            \/* Mobile styles - 1 column *\/\n            @media (max-width: 480px) {\n                .aws-product-grid {\n                    grid-template-columns: 1fr;\n                    gap: 15px;\n                }\n                \n                .aws-product-image {\n                    height: 220px;\n                }\n                \n                .aws-product-content {\n                    padding: 12px;\n                }\n            }\n        <\/style><\/p>\n<h2>Borderlands 4 rompe r\u00e9cords de ventas con ingresos globales de $150 millones y m\u00e1s de 2.5 millones de unidades vendidas<\/h2>\n<p>Desde su lanzamiento el 12 de septiembre, Borderlands 4 ha generado m\u00e1s de $150 millones a nivel mundial gracias a la venta de m\u00e1s de 2.5 millones de unidades, seg\u00fan Alinea Analytics. En Steam, el juego vendi\u00f3 m\u00e1s de 1.3 millones de copias, lo que representa m\u00e1s de $80 millones de sus ingresos totales. Las ventas en consolas han superado el mill\u00f3n de marcas. Poco despu\u00e9s del lanzamiento, el juego lleg\u00f3 a un pico de m\u00e1s de 300,000 jugadores simult\u00e1neos en Steam. La mayor\u00eda de los jugadores est\u00e1n basados en Estados Unidos en ambas plataformas de Steam y PlayStation, seguidos de pa\u00edses como China, Alemania, Reino Unido, Francia y Canad\u00e1. Una parte significativa de la base de jugadores de Borderlands 4 est\u00e1 compuesta por veteranos de la serie. En Steam, el 59% de sus jugadores hab\u00eda jugado anteriormente Borderlands 2, el 51% hab\u00eda jugado Borderlands 3 y el 22% hab\u00eda jugado Tiny Tina&#8217;s Wonderlands. Para los jugadores de PlayStation, donde la membres\u00eda de PS Plus ayud\u00f3 a atraer a nuevos usuarios, el 81% hab\u00eda jugado Borderlands 3, el 64% hab\u00eda jugado The Handsome Collection y el 50% hab\u00eda jugado Tiny Tina&#8217;s Wonderlands.<\/p>\n<h2>Problemas de rendimiento en Borderlands 4 se abordan con actualizaciones y opciones de reembolso para jugadores insatisfechos<\/h2>\n<p>A pesar de su lanzamiento exitoso, la versi\u00f3n para PC de Borderlands 4 enfrent\u00f3 inicialmente quejas sobre problemas de rendimiento. Alinea Analytics anticipa que futuras actualizaciones resolver\u00e1n estos problemas. Abordando estas preocupaciones, el CEO de Gearbox Randy Pitchford declarou en las redes sociales que algunos problemas podr\u00edan deberse a la configuraci\u00f3n del PC de los jugadores y sugiri\u00f3 que los clientes insatisfechos podr\u00edan solicitar reembolsos.<\/p>\n<h2>Por si te lo perdiste<\/h2>\n<p>Noticias emocionantes para los fans de Zelda. El \u00faltimo art\u00edculo de Ahmed Hassan, \u00abZelda: El pr\u00f3ximo juego ofrecer\u00e1 contenido gratuito para los fans leales\u00bb, se sumerge en el lanzamiento pr\u00f3ximo de Hyrule Warriors: Cr\u00f3nicas del Sello en Nintendo Switch 2. Programado para el 6 de noviembre de 2025, este juego no solo promete una historia cautivadora sino que tambi\u00e9n recompensa a los jugadores dedicados con bonus exclusivos dentro del juego ligados a su historial anterior de juegos de Zelda. Publicado el 21 de septiembre de 2025, no te pierdas explorar c\u00f3mo este nuevo cap\u00edtulo se integra en la l\u00ednea oficial de tiempo y contin\u00faa la exitosa serie. Sum\u00e9rgete en todos los detalles <a href=\"https:\/\/playersforlife.com\/fr\/2025\/09\/21\/zelda-prochain-jeu-a-offrir-du-contenu-gratuit-pour-les-fans-fideles\/\" target=\"_blank\" rel=\"noopener noreferrer\">Zelda : Prochain jeu \u00e0 offrir du contenu gratuit pour les fans fid\u00e8les<\/a>. Si eres fan de los roguelikes emocionantes y no puedes esperar para sumergirte en la secuela que est\u00e1 causando revuelo, aseg\u00farate de revisar el \u00faltimo art\u00edculo de Sophie Laurent, \u00abHades 2: \u00bfQu\u00e9 hora ser\u00e1 el juego disponible en PC, Nintendo Switch y Nintendo Switch 2?\u00bb (publicado el 20 de septiembre de 2025). El art\u00edculo se sumerge en todos los detalles del muy esperado lanzamiento de Hades 2, incluyendo su hora de inicio y funciones de guardado cruzado. No te pierdas la emoci\u00f3n &#8211; ve a <a href=\"https:\/\/playersforlife.com\/fr\/2025\/09\/20\/hades-2-a-quelle-heure-le-jeu-sera-t-il-disponible-sur-pc-nintendo-switch-et-nintendo-switch-2\/\" target=\"_blank\" rel=\"noopener noreferrer\">Hades 2 : \u00c0 quelle heure le jeu sera-t-il disponible sur PC, Nintendo Switch et Nintendo Switch 2 ?<\/a> para obtener m\u00e1s informaci\u00f3n. Para aquellos que siguen las \u00faltimas tendencias en hardware de juegos, el \u00faltimo art\u00edculo de Sophie Laurent en Players for Life se sumerge en la \u00faltima estrategia de precios de Microsoft. Publicado el 19 de septiembre de 2025, su art\u00edculo detalla c\u00f3mo las consolas Xbox Series X|S est\u00e1n experimentando otro aumento de precio en el mercado estadounidense a partir del 3 de octubre. Este desarrollo subraya los cambios econ\u00f3micos y afectar\u00e1 a todos los modelos principales<\/p>\n<p><img decoding=\"async\" style=\"width: 100%\" src=\"https:\/\/w.wallhaven.cc\/full\/mp\/wallhaven-mp95o9.jpg\" alt=\"\" title=\"\"><br \/>\n<div class=\"specifications\"><h2><\/h2><p class=\"specifications__disclaimer\"><\/p><div class=\"pcrstb-wrap\"><table class=\"specifications__table\"><thead><tr><th class=\"specifications__key-header\">Specification<\/th><th class=\"specifications__value-header\"><\/th><\/tr><\/thead><tbody><tr class=\"specifications__row\" data-index=\"1\"><td class=\"specifications__key\">Official Name<\/td><td class=\"specifications__value\">Borderlands 4<\/td><\/tr><tr class=\"specifications__row\" data-index=\"2\"><td class=\"specifications__key\">Brief Summary<\/td><td class=\"specifications__value\">See if you have what it takes to go down in history as a legendary Vault Hunter as you search for secret alien treasure, blasting everything in sight.<\/td><\/tr><tr class=\"specifications__row\" data-index=\"3\"><td class=\"specifications__key\">Platforms<\/td><td class=\"specifications__value\">PlayStation 5, PC (Microsoft Windows), Nintendo Switch 2, Xbox Series X|S<\/td><\/tr><tr class=\"specifications__row\" data-index=\"4\"><td class=\"specifications__key\">Released<\/td><td class=\"specifications__value\">September 11, 2025<\/td><\/tr><tr class=\"specifications__row\" data-index=\"5\"><td class=\"specifications__key\">Genre<\/td><td class=\"specifications__value\">Shooter, Role-playing (RPG), Adventure<\/td><\/tr><tr class=\"specifications__row\" data-index=\"6\"><td class=\"specifications__key\">Play Modes<\/td><td class=\"specifications__value\">Single player, Multiplayer, Co-operative<\/td><\/tr><tr class=\"specifications__row\" data-index=\"7\"><td class=\"specifications__key\">Content Rating<\/td><td class=\"specifications__value\">19+<\/td><\/tr><tr class=\"specifications__row\" data-index=\"8\"><td class=\"specifications__key\">Languages<\/td><td class=\"specifications__value\">Chinese (Simplified), English, French, Korean<\/td><\/tr><tr class=\"specifications__row\" data-index=\"9\"><td class=\"specifications__key\">Genre<\/td><td class=\"specifications__value\">Gearbox Software<\/td><\/tr><tr class=\"specifications__row\" data-index=\"10\"><td class=\"specifications__key\">Genre<\/td><td class=\"specifications__value\">2K<\/td><\/tr><tr class=\"specifications__row\" data-index=\"11\"><td class=\"specifications__key\">Ratings<\/td><td class=\"specifications__value\">74\/100 (18 reviews)<\/td><\/tr><\/tbody><\/table><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Borderlands 4 es apreciado por m\u00e1s de 2,5 millones de jugadores en todo el mundo y ha generado una facturaci\u00f3n de 150 millones de d\u00f3lares. En Steam se han vendido m\u00e1s de 1,3 millones de copias.<\/p>\n","protected":false},"author":23,"featured_media":55752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","movie_schema":"","tvshow_schema":"","videogame_schema":"{\"url\":\"https:\/\/www.igdb.com\/games\/borderlands-4\",\"name\":\"Borderlands 4\",\"@type\":\"VideoGame\",\"genre\":[\"Shooter\",\"Role-playing (RPG)\",\"Adventure\"],\"image\":[\"https:\/\/images.igdb.com\/igdb\/image\/upload\/t_720p\/co9zuq.jpg\",\"https:\/\/images.igdb.com\/igdb\/image\/upload\/t_720p\/sctohn.jpg\",\"https:\/\/images.igdb.com\/igdb\/image\/upload\/t_720p\/sctohp.jpg\",\"https:\/\/images.igdb.com\/igdb\/image\/upload\/t_720p\/scwn2v.jpg\",\"https:\/\/images.igdb.com\/igdb\/image\/upload\/t_720p\/scwn2w.jpg\",\"https:\/\/images.igdb.com\/igdb\/image\/upload\/t_720p\/scwn2x.jpg\",\"https:\/\/images.igdb.com\/igdb\/image\/upload\/t_720p\/scwn2y.jpg\",\"https:\/\/images.igdb.com\/igdb\/image\/upload\/t_720p\/scwn2z.jpg\",\"https:\/\/images.igdb.com\/igdb\/image\/upload\/t_720p\/scwn30.jpg\",\"https:\/\/images.igdb.com\/igdb\/image\/upload\/t_720p\/scwn31.jpg\"],\"author\":[{\"name\":\"Gearbox Software\",\"@type\":\"Organization\"}],\"trailer\":[{\"@type\":\"VideoObject\",\"embedUrl\":\"https:\/\/www.youtube.com\/embed\/BXzf6j2Sr5c\"},{\"@type\":\"VideoObject\",\"embedUrl\":\"https:\/\/www.youtube.com\/embed\/ZhKilJFhI3E\"},{\"@type\":\"VideoObject\",\"embedUrl\":\"https:\/\/www.youtube.com\/embed\/5hODQSLU5ZQ\"},{\"@type\":\"VideoObject\",\"embedUrl\":\"https:\/\/www.youtube.com\/embed\/AxaPpkie6t4\"},{\"@type\":\"VideoObject\",\"embedUrl\":\"https:\/\/www.youtube.com\/embed\/z4qeqPZJTaE\"},{\"@type\":\"VideoObject\",\"embedUrl\":\"https:\/\/www.youtube.com\/embed\/fUNd0bHHWlo\"}],\"@context\":\"https:\/\/schema.org\",\"keywords\":\"steam achievements, cross-platform, Action, Science fiction\",\"playMode\":[\"Single player\",\"Multiplayer\",\"Co-operative\"],\"publisher\":[{\"name\":\"2K\",\"@type\":\"Organization\"}],\"inLanguage\":[\"Chinese (Simplified)\",\"English\",\"French\",\"Korean\"],\"dateCreated\":\"2024-08-20T18:04:11.000Z\",\"description\":\"See if you have what it takes to go down in history as a legendary Vault Hunter as you search for secret alien treasure, blasting everything in sight.\",\"dateModified\":\"2025-09-22T12:52:43.000Z\",\"gamePlatform\":[\"PlayStation 5\",\"PC (Microsoft Windows)\",\"Nintendo Switch 2\",\"Xbox Series X|S\"],\"alternateName\":[\"Borderlands4.exe\",\"BORDERLANDS 4\"],\"contentRating\":\"19+\",\"datePublished\":\"2025-09-11T00:00:00.000Z\",\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingCount\":18,\"ratingValue\":74}}","meta_description":"\"Borderlands 4 ya es un \u00e9xito: m\u00e1s de 2,5 millones de jugadores y $150 millones en ingresos.\"","meta_keywords":"Borderlands 4, millones de jugadores, Borderlands 3, Gearbox, juegos de disparos en primera persona","meta_author":"Aitor Calvente","meta_robots":"index, follow","meta_language":"en","twitter_card":"summary_large_image","twitter_title":"\"Borderlands 4 supera los 2,5 millones de jugadores\"","twitter_description":"Conquista el universo junto a m\u00e1s de 2.5 millones de jugadores en Borderlands 4","twitter_site":"","twitter_site_id":"","twitter_creator":"","twitter_creator_id":"","twitter_image":"https:\/\/assetsio.gnwcdn.com\/Borderlands-4-Endgame-Postlaunch_08-29-25_001-1440x810.jpg","twitter_image_alt":"","twitter_app_name_iphone":"","twitter_app_id_iphone":"","twitter_app_url_iphone":"","twitter_app_name_ipad":"","twitter_app_id_ipad":"","twitter_app_url_ipad":"","twitter_app_name_googleplay":"","twitter_app_id_googleplay":"","twitter_app_url_googleplay":"","twitter_player":"","twitter_player_width":0,"twitter_player_height":0,"twitter_player_stream":"","og_title":"\"Borderlands 4 supera los 2,5 millones de jugadores\"","og_type":"article","og_url":"https:\/\/playersforlife.com\/es\/2025\/09\/22\/borderlands-4-ya-ha-conquistado-a-mas-de-2-5-millones-de-jugadores\/","og_image":"https:\/\/assetsio.gnwcdn.com\/Borderlands-4-Endgame-Postlaunch_08-29-25_001-1440x810.jpg","og_image_secure_url":"https:\/\/assetsio.gnwcdn.com\/Borderlands-4-Endgame-Postlaunch_08-29-25_001-1440x810.jpg","og_image_type":"image\/jpeg","og_image_width":0,"og_image_height":0,"og_image_alt":"","og_description":"Conquista el universo junto a m\u00e1s de 2.5 millones de jugadores en Borderlands 4","og_site_name":"PlayersForLife.com","og_locale":"en_US","og_article_published_time":"2025-09-22T14:38:44","og_article_modified_time":"2025-09-22T14:38:44","og_article_author":"Aitor Calvente","og_article_section":"Business","og_article_tag":["Action"],"og_video":"https:\/\/www.youtube.com\/embed\/evu6pNHi8rE","og_video_secure_url":"https:\/\/www.youtube.com\/embed\/evu6pNHi8rE","og_video_type":"","og_video_width":0,"og_video_height":0,"og_audio":"","og_audio_secure_url":"","og_audio_type":"","footnotes":""},"categories":[33],"tags":[42,45],"class_list":["post-55765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business","tag-action","tag-mixed"],"lang":"es","original_post_id":null,"featured_image_urls":{"full":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37.jpg",1440,810,false],"thumbnail":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-150x150.jpg",150,150,true],"medium":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-300x169.jpg",300,169,true],"medium_large":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-768x432.jpg",768,432,true],"large":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37.jpg",1440,810,false],"2048x2048":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37.jpg",1440,810,false],"penci-single-full":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37.jpg",1440,810,false],"penci-slider-full-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-1440x800.jpg",1440,800,true],"penci-full-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-1170x658.jpg",1170,658,true],"penci-slider-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-1170x663.jpg",1170,663,true],"penci-magazine-slider":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-780x516.jpg",780,516,true],"penci-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-585x390.jpg",585,390,true],"penci-masonry-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-585x329.jpg",585,329,true],"penci-thumb-square":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-585x585.jpg",585,585,true],"penci-thumb-vertical":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-480x650.jpg",480,650,true],"penci-thumb-small":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-263x175.jpg",263,175,true],"penci-recipe-1200x1200":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-1200x810.jpg",1200,810,true],"penci-recipe-1200x900":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-1200x810.jpg",1200,810,true],"penci-recipe-1200x675":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/09\/image_2025-09-Sep-22-2025_10-35-37-1200x675.jpg",1200,675,true]},"author_info":{"info":["Aitor Calvente"]},"category_info":"<a href=\"https:\/\/playersforlife.com\/category\/business\/\" rel=\"category tag\">Business<\/a>","tag_info":"Business","comment_count":"0","_links":{"self":[{"href":"https:\/\/playersforlife.com\/es\/wp-json\/wp\/v2\/posts\/55765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/playersforlife.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/playersforlife.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/playersforlife.com\/es\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/playersforlife.com\/es\/wp-json\/wp\/v2\/comments?post=55765"}],"version-history":[{"count":1,"href":"https:\/\/playersforlife.com\/es\/wp-json\/wp\/v2\/posts\/55765\/revisions"}],"predecessor-version":[{"id":55766,"href":"https:\/\/playersforlife.com\/es\/wp-json\/wp\/v2\/posts\/55765\/revisions\/55766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/playersforlife.com\/es\/wp-json\/wp\/v2\/media\/55752"}],"wp:attachment":[{"href":"https:\/\/playersforlife.com\/es\/wp-json\/wp\/v2\/media?parent=55765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/playersforlife.com\/es\/wp-json\/wp\/v2\/categories?post=55765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/playersforlife.com\/es\/wp-json\/wp\/v2\/tags?post=55765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}