{"id":18809,"date":"2025-03-04T21:02:00","date_gmt":"2025-03-04T21:02:00","guid":{"rendered":"https:\/\/playersforlife.com\/2025\/03\/04\/acclaim-kehrt-nach-20-jahren-insolvenz-zuruck-will-klassische-serien-wiederbeleben\/"},"modified":"2025-07-31T04:03:31","modified_gmt":"2025-07-31T04:03:31","slug":"acclaim-kehrt-nach-20-jahren-insolvenz-zuruck-will-klassische-serien-wiederbeleben","status":"publish","type":"post","link":"https:\/\/playersforlife.com\/de\/2025\/03\/04\/acclaim-kehrt-nach-20-jahren-insolvenz-zuruck-will-klassische-serien-wiederbeleben\/","title":{"rendered":"Acclaim kehrt nach 20 Jahren Insolvenz zur\u00fcck, will klassische Serien wiederbeleben"},"content":{"rendered":"<p>\u00dcberpr\u00fcfung des Acclaim-Logos zehn Jahre nach seiner Aufl\u00f6sung geh\u00f6rte nicht in unseren 2025-Plan, dennoch tauchte am sonnigen 4. M\u00e4rz (auf der Seite von Ile-de-France) einer der prominentesten Verlage der 1990er Jahre wieder auf. &#8222;Acclaim ist zur\u00fcck&#8220;, wie die neue Logo-Darstellung nahelegt, und diese Wiederkunft l\u00f6ste nat\u00fcrlich erhebliche Diskussionen aus, insbesondere bei denen, die in den 1980er und 1990er Jahren Videospiele spielten. Titel wie NBA Jam, Mortal Kombat, Extreme G, Re-Volt, Turok und selbst fr\u00fche Burnout-Ver\u00f6ffentlichungen waren mit Acclaim verbunden. Diese R\u00fcckkehr wird langsam geschehen, beginnend mit der Unterst\u00fctzung von unabh\u00e4ngigen Studios, um die klassischen Serien wiederzubeleben, indem sie finanzielle Mittel, Marketing und \u00d6ffentlichkeitsarbeit zur Verf\u00fcgung stellen, um diese Indie-Studios die notwendige Sichtbarkeit zu geben. Das Team, das das Label relancieren soll, besteht aus vier Individuen unterschiedlicher Hintergr\u00fcnde: Alex Josef, ehemaliger Gr\u00fcnder von Graffiti Games; Jeff Jarrett, ehemaliger Wrestler und wichtiger Mitarbeiter bei Global Force Entertainment; Russell Binder, der bei Striker Entertainment arbeitete; und Mark Caplan aus Ridge Partners.<\/p>\n<p>&#8222;Es ist eine Ehre und ein Vergn\u00fcgen, Acclaim wieder an die Spitze der Spielesbranche zu f\u00fchren&#8220;, erkl\u00e4rte Alex Josef in einem Pressemitteilung. Er erg\u00e4nzte: \u201eWir haben Gl\u00fcck mit einer au\u00dferordentlich talentierten Mannschaft und haben bereits gro\u00dfartige unabh\u00e4ngige Titel abgesichert, die wir bald offenlegen werden.&#8220; F\u00fcr \u00fcber drei Jahrzehnte war ich in beiden Wrestling- und Videospielbranchen aktiv und es freut mich, jetzt Partner bei der Wiederauferstehung von Acclaim zu sein, einem legend\u00e4ren Verlag, der f\u00fcr die Ver\u00f6ffentlichung vieler legend\u00e4rer Spiele der 80er und 90er bekannt war, sagte Jarrett. \u201eVon meinen fr\u00fchen Tagen an, in denen ich an den erfolgreichen 16-Bit-WWF-Titeln von Acclaim arbeitete, bis zu meiner Erfahrung beim Erstellen der TNA Wrestling Series, die den ersten Vollzeit-Videospielwrestler einer Belegschaft einf\u00fchrte, habe ich pers\u00f6nlich die Wirkung gro\u00dfer Spiele auf Spieler und Fans miterlebt. Die Wiederbelebung von Acclaim bietet eine Chance, dem gleichen Ma\u00df an Leidenschaft und Engagement einer neuen Generation zu teilen, und ich freue mich dar\u00fcber, dabei mitzuwirken.\u201c<\/p>\n<p>Acclaims Wachstumskonzept wird von Phil Toronto unterst\u00fctzt, einem Partner bei VaynerFund, und Eric Vogel, einem Partner bei JET Management. Ihre Expertise im Bereich Investment und Management soll helfen, \u201eeine Umgebung zu schaffen, die Bildung unabh\u00e4ngiger Entwickler f\u00f6rdert und langfristigen Erfolg sichert\u201c. Ob welche historischen geistigen Eigent\u00fcmer das neue Acclaim versuchen wird, wiederzubeleben, ist noch offen. Seitdem Mortal Kombat von Warner Bros Games besitzt, geh\u00f6rt Burnout zu Electronic Arts und das kommende Turok Origins wird von Saber Interactive (Warhammer Space Marine 2) und Universal verwaltet, k\u00f6nnte Extreme G ein attraktiver Kandidat f\u00fcr die Wiederbelebung sein.<\/p>\n<p><iframe title=\"Extreme-G 3 Review - &quot;F-Zero with Bikes&quot; | GameCube Galaxy\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/WsL_sC5BXvY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach 20 Jahren im Ruhestand kehrt Acclaim zur\u00fcck, geleitet von einer erfahrenen Mannschaft, die sich daran macht, alte Marken wie Mortal Kombat und Extreme G neu zu beleben, indem sie Indie-Entwicklern Ressourcen und Investmentkompetenz zur Verf\u00fcgung stellt.<\/p>\n","protected":false},"author":17,"featured_media":3580,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","movie_schema":"","tvshow_schema":"","videogame_schema":"","meta_description":"Acclaim returns after 20 years to revive classic gaming franchises via indie studio partnerships","meta_keywords":"seo-gaming, indie-game-development, revive-classic-franchises, video-game-publishing, game-industry-news","meta_author":"Theo Drexler","meta_robots":"index, follow","meta_language":"en","twitter_card":"summary_large_image","twitter_title":"Acclaim returns: reviving classic game franchises","twitter_description":"Acclaim returns after 20 years to revive classic gaming franchises","twitter_site":"","twitter_site_id":"","twitter_creator":"","twitter_creator_id":"","twitter_image":"https:\/\/static1.thegamerimages.com\/wordpress\/wp-content\/uploads\/sharedimages\/2024\/11\/extreme-g-press-image-6.jpg","twitter_image_alt":"","twitter_app_name_iphone":"","twitter_app_id_iphone":"","twitter_app_url_iphone":"","twitter_app_name_ipad":"","twitter_app_id_ipad":"","twitter_app_url_ipad":"","twitter_app_name_googleplay":"","twitter_app_id_googleplay":"","twitter_app_url_googleplay":"","twitter_player":"","twitter_player_width":0,"twitter_player_height":0,"twitter_player_stream":"","og_title":"Acclaim returns: reviving classic game franchises","og_type":"article","og_url":"https:\/\/playersforlife.com\/de\/2025\/03\/04\/acclaim-kehrt-nach-20-jahren-insolvenz-zuruck-will-klassische-serien-wiederbeleben\/","og_image":"https:\/\/static1.thegamerimages.com\/wordpress\/wp-content\/uploads\/sharedimages\/2024\/11\/extreme-g-press-image-6.jpg","og_image_secure_url":"https:\/\/static1.thegamerimages.com\/wordpress\/wp-content\/uploads\/sharedimages\/2024\/11\/extreme-g-press-image-6.jpg","og_image_type":"image\/jpeg","og_image_width":0,"og_image_height":0,"og_image_alt":"","og_description":"Acclaim returns after 20 years to revive classic gaming franchises","og_site_name":"PlayersForLife.com","og_locale":"en_US","og_article_published_time":"2025-03-04T04:03:00","og_article_modified_time":"2025-03-04T04:03:00","og_article_author":"Theo Drexler","og_article_section":"Business","og_article_tag":["Action"],"og_video":"https:\/\/www.youtube.com\/embed\/IidCAuyAiF8","og_video_secure_url":"https:\/\/www.youtube.com\/embed\/IidCAuyAiF8","og_video_type":"","og_video_width":0,"og_video_height":0,"og_audio":"","og_audio_secure_url":"","og_audio_type":"","footnotes":""},"categories":[33],"tags":[42,44,45,47,48,50],"class_list":["post-18809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business","tag-action","tag-fighting","tag-mixed","tag-racing","tag-rpg","tag-shooter"],"lang":"de","original_post_id":null,"featured_image_urls":{"full":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false],"thumbnail":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6-150x150.jpg",150,150,true],"medium":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6-300x225.jpg",300,225,true],"medium_large":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false],"large":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false],"1536x1536":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false],"2048x2048":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false],"penci-single-full":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false],"penci-slider-full-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false],"penci-full-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false],"penci-slider-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false],"penci-magazine-slider":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false],"penci-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",520,390,false],"penci-masonry-thumb":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",585,439,false],"penci-thumb-square":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",585,439,false],"penci-thumb-vertical":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",480,360,false],"penci-thumb-small":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",233,175,false],"penci-recipe-1200x1200":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false],"penci-recipe-1200x900":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false],"penci-recipe-1200x675":["https:\/\/playersforlife.com\/wp-content\/uploads\/2025\/06\/extreme-g-press-image-6.jpg",640,480,false]},"author_info":{"info":["Theo Drexler"]},"category_info":"<a href=\"https:\/\/playersforlife.com\/category\/business\/\" rel=\"category tag\">Business<\/a>","tag_info":"Business","comment_count":"0","_links":{"self":[{"href":"https:\/\/playersforlife.com\/de\/wp-json\/wp\/v2\/posts\/18809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/playersforlife.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/playersforlife.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/playersforlife.com\/de\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/playersforlife.com\/de\/wp-json\/wp\/v2\/comments?post=18809"}],"version-history":[{"count":1,"href":"https:\/\/playersforlife.com\/de\/wp-json\/wp\/v2\/posts\/18809\/revisions"}],"predecessor-version":[{"id":18810,"href":"https:\/\/playersforlife.com\/de\/wp-json\/wp\/v2\/posts\/18809\/revisions\/18810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/playersforlife.com\/de\/wp-json\/wp\/v2\/media\/3580"}],"wp:attachment":[{"href":"https:\/\/playersforlife.com\/de\/wp-json\/wp\/v2\/media?parent=18809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/playersforlife.com\/de\/wp-json\/wp\/v2\/categories?post=18809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/playersforlife.com\/de\/wp-json\/wp\/v2\/tags?post=18809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}